{"id":2806,"date":"2020-08-19T07:12:36","date_gmt":"2020-08-19T11:12:36","guid":{"rendered":"https:\/\/www.fermedescouleurs.com\/nuestra-granja\/"},"modified":"2026-04-21T17:02:37","modified_gmt":"2026-04-21T21:02:37","slug":"nuestra-granja","status":"publish","type":"page","link":"https:\/\/www.fermedescouleurs.com\/es\/nuestra-granja\/","title":{"rendered":"Nuestra granja"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-2f75c305 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-bada88a3 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><div class=\"uagb-ifb-separator\"><\/div><h1 class=\"uagb-ifb-title\">Nuestra Granja<\/h1><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b6034324\"><p class=\"uagb-desc-text\">Ubicada en Saint-Justine-de-Newton, nuestra granja de hortalizas implementa m\u00e9todos innovadores para mejorar la calidad de nuestras verduras y frutas, respetando el medio ambiente.<\/p><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-80e06480 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-dac02f5d uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><span class=\"uagb-ifb-title-prefix\">Nuestro objetivo principal<\/span><div class=\"uagb-ifb-separator\"><\/div><h2 class=\"uagb-ifb-title\">Ofrecer productos frescos, locales y ecol\u00f3gicos, garant\u00eda de confianza y transparencia.<\/h2><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e2c74950\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-48b25caa\"><p class=\"uagb-desc-text\">Ubicada en la regi\u00f3n de Vaudreuil-Soulanges, m\u00e1s precisamente en Sainte-Justine-de-Newton, en Mont\u00e9r\u00e9gie, nuestra granja se compromete a proporcionar alimentos locales y de calidad cerca de ti.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6ae7c5ca\"><p class=\"uagb-desc-text\">Servimos las siguientes regiones en Quebec: Vaudreuil-Soulanges, Valleyfield y el oeste de la isla.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f6eaa56f\"><p class=\"uagb-desc-text\">Servimos las siguientes regiones en Ontario: East Hawkesbury, North Glengarry &amp; South Glengarry (hasta la carretera 34)<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4c5912d0\">\n<div class=\"wp-block-uagb-container uagb-block-0ef47414\">\n<div class=\"wp-block-uagb-info-box uagb-block-ea0aa216 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><div class=\"uagb-ifb-separator\"><\/div><h2 class=\"uagb-ifb-title\">Nuestra misi\u00f3n<\/h2><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-282ba837\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c59a0242\"><p class=\"uagb-desc-text\">En Ferme des Couleurs, nuestra misi\u00f3n es cultivar una abundancia de vida a trav\u00e9s de una agricultura eco-intensiva, respetuosa con el medio ambiente y la comunidad. Nos comprometemos a ofrecer frutas y verduras de la m\u00e1s alta calidad, cultivadas con esmero para preservar la salud del suelo y la vitalidad de los ecosistemas.<br\/><br\/><\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f2a7b91a\">\n<div class=\"wp-block-uagb-container uagb-block-23315aec\">\n<div class=\"wp-block-uagb-info-box uagb-block-fe600cd0 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><div class=\"uagb-ifb-separator\"><\/div><h2 class=\"uagb-ifb-title\">Nuestro Objetivo<\/h2><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b850426f\">\n<p class=\"wp-block-paragraph\">Creemos firmemente en la sostenibilidad ambiental, por eso implementamos pr\u00e1cticas agr\u00edcolas que favorecen la biodiversidad, preservan los recursos naturales y reducen nuestra huella de carbono. Nos esforzamos por crear un equilibrio armonioso entre la agricultura y la naturaleza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprometidos con nuestra comunidad local, apoyamos la econom\u00eda local proporcionando alimentos sanos y coloridos a nuestros vecinos, fortaleciendo as\u00ed los lazos que nos unen.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2c11bb62\">\n<div class=\"wp-block-uagb-container uagb-block-4bb02dea\">\n<div class=\"wp-block-uagb-info-box uagb-block-09c80fa6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><div class=\"uagb-ifb-separator\"><\/div><h2 class=\"uagb-ifb-title\">Nuestra visi\u00f3n<\/h2><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-23a3df7e\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a3c9656e\"><p class=\"uagb-desc-text\">A trav\u00e9s de estos compromisos, aspiramos a ser un modelo de empresa pr\u00f3spera, guiada por valores de respeto, integridad y responsabilidad hacia la tierra y la comunidad. Ferme des Couleurs es m\u00e1s que una simple empresa agr\u00edcola; es una expresi\u00f3n de nuestro compromiso con un futuro sostenible y pr\u00f3spero para todos.<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-49349470 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.fermedescouleurs.com\/wp-content\/uploads\/2020\/08\/horticulturist-seeding-plants.jpg\" alt=\"\" class=\"uag-image-96\" width=\"1200\" height=\"640\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-3a6f29a2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2eb52279\"><h2 class=\"uagb-heading-text\">Un equipo familiar<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-58785dec\">\n<div class=\"wp-block-uagb-team uagb-team__image-position-above uagb-team__align-center uagb-team__stack-tablet uagb-block-26e4fefd\"><div class=\"uagb-team__content\"><img decoding=\"async\" class=\"uagb-team__image-crop-circle\" src=\"https:\/\/www.fermedescouleurs.com\/wp-content\/uploads\/2023\/12\/logo6.jpg\" alt=\"\" height=\"350\" width=\"350\" loading=\"lazy\"\/><h3 class=\"uagb-team__title\">Carolane<\/h3><span class=\"uagb-team__prefix\">Horticultora y Presidenta<\/span><p class=\"uagb-team__desc\">Nuestra presidenta, como una loba atenta a su manada, vela con dedicaci\u00f3n por nuestra peque\u00f1a empresa de hortalizas, buscando siempre hacer brillar la sonrisa y la satisfacci\u00f3n en los rostros de nuestros clientes.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-team uagb-team__image-position-above uagb-team__align-center uagb-team__stack-tablet uagb-block-fcc186b4\"><div class=\"uagb-team__content\"><img decoding=\"async\" class=\"uagb-team__image-crop-circle\" src=\"https:\/\/www.fermedescouleurs.com\/wp-content\/uploads\/2023\/12\/logo6.jpg\" alt=\"\" height=\"350\" width=\"350\" loading=\"lazy\"\/><h3 class=\"uagb-team__title\">Jonathan<\/h3><span class=\"uagb-team__prefix\">Horticultor y Controlador financiero<\/span><p class=\"uagb-team__desc\">Aqu\u00ed est\u00e1 nuestro controlador y horticultor, un artesano de la tierra y las finanzas que, con una c\u00e1lida sonrisa, vela por el equilibrio armonioso entre los n\u00fameros y las cosechas, con el objetivo de hacer florecer nuestra granja y nuestra comunidad.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-team uagb-team__image-position-above uagb-team__align-center uagb-team__stack-tablet uagb-block-be024991\"><div class=\"uagb-team__content\"><img decoding=\"async\" class=\"uagb-team__image-crop-circle\" src=\"https:\/\/www.fermedescouleurs.com\/wp-content\/uploads\/2023\/12\/logo6.jpg\" alt=\"\" height=\"350\" width=\"350\" loading=\"lazy\"\/><h3 class=\"uagb-team__title\">\u00a1Pr\u00f3ximamente!<\/h3><span class=\"uagb-team__prefix\">Manitas<\/span><p class=\"uagb-team__desc\"><\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-30587729 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-79dc3eb6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><div class=\"uagb-ifb-separator\"><\/div><h2 class=\"uagb-ifb-title\">Suscr\u00edbete para disfrutar de nuestras ofertas exclusivas.<\/h2><\/div><p class=\"uagb-ifb-desc\"><br\/>Nos esforzamos por ofrecerte un servicio de calidad, al mismo tiempo que te proponemos interesantes ofertas semanales.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-ast-global-color-5-color has-text-color has-link-color has-small-font-size wp-elements-1 is-layout-constrained wp-block-group-is-layout-constrained\"><div class='fluentform ff-default fluentform_wrapper_2  ff_guten_block ff_guten_block-2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Subscription Form<\/legend><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"57\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><input type='hidden' name='__fluent_form_embded_post_id' value='2806' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"bd7b6d21f7\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/2806\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_names_first_name_' id='label_ff_2_names_first_name_' >Pr\u00e9nom<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_2_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Saisissez votre pr\u00e9nom\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_2_names_last_name_' id='label_ff_2_names_last_name_' >Nom de famille<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_2_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Saisissez votre nom de famille\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_email' id='label_ff_2_email' aria-label=\"Courriel\">Courriel<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_email\" class=\"ff-el-form-control\" placeholder=\"Votre adresse courriel\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='Je consens \u00e0 ce que ce site stocke les informations que j\u2019ai envoy\u00e9es afin de pouvoir r\u00e9pondre \u00e0 ma demande.' class='ff-el-form-check-label ff_tc_label' for=gdpr-agreement_2e3b7e368ec30da217707eab3052d17c><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"gdpr-agreement\" class=\"ff-el-form-check-input ff_gdpr_field\" data-name=\"gdpr-agreement\" id=\"gdpr-agreement_2e3b7e368ec30da217707eab3052d17c\"  value='on' aria-invalid='false' aria-required=true><\/span> <div class='ff_t_c'>Je consens \u00e0 ce que ce site stocke les informations que j\u2019ai envoy\u00e9es afin de pouvoir r\u00e9pondre \u00e0 ma demande.<\/div><\/label><\/div><\/div><div class='ff-el-group ' ><div class='ff-el-input--content'><div data-fluent_id='2' name='g-recaptcha-response'><div\n\t\tdata-sitekey='6LeHygQrAAAAAEjXcFjT849J69DHERaLzJvHrlMS'\n\t\tid='fluentform-recaptcha-2-1'\n\t\tclass='ff-el-recaptcha g-recaptcha'\n\t\tdata-callback='fluentFormrecaptchaSuccessCallback'><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group ff-text-left ff_submit_btn_wrapper ff_submit_btn_wrapper_custom'><button class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\" type=\"submit\" name=\"custom_submit_button-2_1\" data-name=\"custom_submit_button-2_1\"  aria-label=\"S&#039;inscrire\">S&#8217;inscrire<\/button><style>form.fluent_form_2 .ff-btn-submit { background-color: #67C23A; color: #ffffff; }<\/style><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><\/div><\/div><\/fieldset><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_1 ff-form-loading_errors ff_form_instance_2_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_1 = {\"id\":\"2\",\"ajaxUrl\":\"https:\\\/\\\/www.fermedescouleurs.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_1\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"Ce champ doit contenir un e-mail valide\"}},\"gdpr-agreement\":{\"required\":{\"value\":true,\"message\":\"Este campo es obligatorio\",\"global_message\":\"Ce champ est obligatoire\",\"global\":true}},\"g-recaptcha-response\":[]},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n            <\/div>\n<\/div><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicada en Saint-Justine-de-Newton, nuestra granja de hortalizas implementa m\u00e9todos innovadores para mejorar la calidad de nuestras verduras y frutas, respetando el medio ambiente. Ubicada en la regi\u00f3n de Vaudreuil-Soulanges, m\u00e1s precisamente en Sainte-Justine-de-Newton, en Mont\u00e9r\u00e9gie, nuestra granja se compromete a proporcionar alimentos locales y de calidad cerca de ti. Servimos las siguientes regiones en Quebec: [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"plain-container","ast-site-content-layout":"normal-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2806","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"job-image":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false,"dgwt-wcas-product-suggestion":false},"uagb_author_info":{"display_name":"Evalnor Solutions","author_link":"https:\/\/www.fermedescouleurs.com\/es\/author\/evalnor\/"},"uagb_comment_info":0,"uagb_excerpt":"Ubicada en Saint-Justine-de-Newton, nuestra granja de hortalizas implementa m\u00e9todos innovadores para mejorar la calidad de nuestras verduras y frutas, respetando el medio ambiente. Ubicada en la regi\u00f3n de Vaudreuil-Soulanges, m\u00e1s precisamente en Sainte-Justine-de-Newton, en Mont\u00e9r\u00e9gie, nuestra granja se compromete a proporcionar alimentos locales y de calidad cerca de ti. Servimos las siguientes regiones en Quebec:&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/pages\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":8,"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/pages\/2806\/revisions"}],"predecessor-version":[{"id":3438,"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/pages\/2806\/revisions\/3438"}],"wp:attachment":[{"href":"https:\/\/www.fermedescouleurs.com\/es\/wp-json\/wp\/v2\/media?parent=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}